{"id":8625,"date":"2023-05-04T10:58:53","date_gmt":"2023-05-04T02:58:53","guid":{"rendered":"https:\/\/230411wadmp3.adwebcloud.com\/%products_cat%\/athens-portoro-gold-marble-floor-tiles\/"},"modified":"2023-07-09T15:53:10","modified_gmt":"2023-07-09T07:53:10","slug":"athens-portoro-gold-marble-floor-tiles","status":"publish","type":"products","link":"https:\/\/whitemarblegranite.com\/es\/product\/athens-portoro-gold-marble-floor-tiles\/","title":{"rendered":"Baldosas de m\u00e1rmol Athens Portoro Gold"},"content":{"rendered":"<p><strong>Baldosas de m\u00e1rmol Athens negro y dorado de Portoro para proyectos de interiores<\/strong><\/p>\n<p>El m\u00e1rmol Athens Portoro, tambi\u00e9n conocido como m\u00e1rmol negro y dorado, es una fina variedad de m\u00e1rmol negro y dorado chino. Es uno de los m\u00e1s bellos entre los m\u00e1rmoles negros policrom\u00e1ticos de Portoro. Esta preciosa piedra china presenta un color negro intenso y brillante con vetas doradas que van del amarillo intenso al color miel. Este m\u00e1rmol Portoro chino no tiene ninguna diferencia en color y textura, excepto que el patr\u00f3n es diferente del Portoro dorado italiano, que es un sustituto del m\u00e1rmol Portoro italiano y las baldosas de suelo de m\u00e1rmol Portoro dorado de Atenas son las preferidas por contratistas, constructores y empresas de dise\u00f1o.<\/p>\n<p>El profundo e intenso color negro de las baldosas de m\u00e1rmol Athens Portoro Gold da la apariencia de una textura casi aterciopelada, que es particularmente observable cuando las losas de m\u00e1rmol Athen Portoro est\u00e1n pulidas. Estas baldosas y losas de m\u00e1rmol negro Portoro de Atenas pulidas parecen como si se hubiera vertido oro directamente sobre la piedra. Las vetas, rayas, manchas y sombras de este m\u00e1rmol negro y dorado son el resultado de sustancias de pirita y ocre-limonita.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/whitemarblegranite.com\/wp-content\/uploads\/2023\/05\/20211205141707dec57b43c7c54a79a4ac6051b1b71333.jpg\" style=\"width: 380px;height: 380px\" title=\"Baldosas de m\u00e1rmol Athens Gold Portoro\" width=\"380\" height=\"380\" border=\"0\" vspace=\"0\" alt=\"Baldosas de m\u00e1rmol Athens Gold Portoro\" \/><img decoding=\"async\" src=\"http:\/\/whitemarblegranite.com\/wp-content\/uploads\/2023\/05\/20211205141707f9c64ccef40a4675ac729ed01fb9da9b.jpg\" title=\"Baldosas de m\u00e1rmol Athens Portoro\" width=\"380\" height=\"380\" border=\"0\" vspace=\"0\" alt=\"Baldosas de m\u00e1rmol Athens Portoro\" style=\"width: 380px;height: 380px\" \/><\/p>\n<table style=\"width:100%\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\" class=\"table\">\n<tbody>\n<tr class=\"firstRow\">\n<td>Material<\/td>\n<td>100% baldosas de m\u00e1rmol natural negro y dorado Athens Portoro<\/td>\n<\/tr>\n<tr>\n<td>Acabado de superficies<\/td>\n<td>Pulido, apomazado, flameado, arenado, abujardado, desbastado, etc.&nbsp;<\/td>\n<\/tr>\n<tr>\n<td>Borde disponible<\/td>\n<td>Pulido, abujardado, plano, flameado, biselado, bisel de pico, Ogee, Cove, Dupont, laminado, no laminado, etc.<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\" colspan=\"1\">Talla<\/p>\n<p><\/td>\n<td>\n<p>Losa:<\/p>\n<p>1800(hasta) x 600(hasta)mm<\/p>\n<p>1800(hasta) x 700(hasta)mm<\/p>\n<p>2400(hasta) x 1200(hasta)mm<\/p>\n<p>2800(hasta) x 1500(hasta)mm, etc.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p style=\"margin-top: 0px;margin-bottom: 0px;padding: 0px\">Azulejos:<\/p>\n<p style=\"margin-top: 0px;margin-bottom: 0px;padding: 0px\">305 x 305 mm<\/p>\n<p style=\"margin-top: 0px;margin-bottom: 0px;padding: 0px\">400 x 400 mm<\/p>\n<p style=\"margin-top: 0px;margin-bottom: 0px;padding: 0px\">457 x 457 mm<\/p>\n<p style=\"margin-top: 0px;margin-bottom: 0px;padding: 0px\">600 x 600 mm<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Tama\u00f1o personalizable<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Espesor<\/td>\n<td>10\/15\/18\/20\/25\/30 mm, etc.<\/td>\n<\/tr>\n<tr>\n<td>Utilizaci\u00f3n<\/td>\n<td>Decoraci\u00f3n interior\/exterior, Para suelo o pared, Encimeras, Encimeras de lavabo<\/td>\n<\/tr>\n<tr>\n<td>Embalaje<\/td>\n<td>Caja de madera marinera<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img decoding=\"async\" src=\"http:\/\/whitemarblegranite.com\/wp-content\/uploads\/2023\/05\/20211205141708924fd5cca09c494b8b06902516ef25b4.jpg\" title=\"Baldosas de m\u00e1rmol Athens Portoro\" \/><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/whitemarblegranite.com\/wp-content\/uploads\/2023\/05\/20211205141711c80bb1b5058348cfaab16b5786a48309.jpg\" title=\"Baldosas de m\u00e1rmol Athens Portoro\" \/><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/whitemarblegranite.com\/wp-content\/uploads\/2023\/05\/2021120514175501854c7bbd204ddaa5acd7baec1b84ec.jpg\" title=\"ESTA F\u00c1BRICA DE PIEDRA \" alt=\"ESTA F\u00c1BRICA DE PIEDRA \" \/><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/whitemarblegranite.com\/wp-content\/uploads\/2023\/05\/20210828230749ae88c405d79543db8cf443895b9a1a34.jpg\" title=\"1-FAQ\" \/><\/p>\n<p><\/p>\n<p>\u00bfQu\u00e9 superficie de baldosas de m\u00e1rmol son perfectas para suelos interiores?<\/p>\n<p>M\u00e1rmol pulido: La opci\u00f3n m\u00e1s popular para suelos de m\u00e1rmol tiene un aspecto muy brillante, que se consigue esmerilando la superficie con una m\u00e1quina pulidora de piedra. El pulido resalta las vetas del m\u00e1rmol y confiere al suelo un aspecto radiante y lujoso. Con el mantenimiento adecuado (v\u00e9ase m\u00e1s abajo), el m\u00e1rmol pulido conservar\u00e1 un acabado reflectante durante muchos a\u00f1os.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/whitemarblegranite.com\/wp-content\/uploads\/2023\/05\/20210828230751b9bb6772281e431195de4a8bd63770f1.jpg\" title=\"2-Cont\u00e1ctenos ahora de Esta Stone\" \/><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo: Athens Nero Portoro Baldosas De M\u00e1rmol Para Interiores Suelo Y Pared<br \/>\nMaterial: M\u00e1rmol Portoro Oro Atenas <br \/>\nSize:600x300mm;1200x1200mm<br \/>\nEspesor: 18,20,30mm<br \/>\nSuperficie: Pulido<br \/>\nMOQ: 100 SQM<br \/>\nMarca: ESTA STONE<br \/>\nAplicaci\u00f3n: Casas, chalets, hoteles y otros proyectos inmobiliarios<\/p>","protected":false},"featured_media":8631,"template":"","adweb_product_categories":[46],"adweb_product_tags":[541,209,36,35,34,332,107,38,101,33,52,322,37],"class_list":["post-8625","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-marble-tiles","adweb_product_tag-athens-portoro-gold-marble-floor-tiles","adweb_product_tag-calacatta-grey-quartzite","adweb_product_tag-customized","adweb_product_tag-factory","adweb_product_tag-manufacturers","adweb_product_tag-marble-columns-cladding-tiles","adweb_product_tag-prefab-quartz-stone-tops","adweb_product_tag-projects","adweb_product_tag-sodalite-blue-granite-floor-tile","adweb_product_tag-suppliers","adweb_product_tag-viscon-white-granite","adweb_product_tag-white-marble-flower-carving-fireplace","adweb_product_tag-wholesale"],"gallery":[8631,8631,10482,10483,10484],"order":null,"acf":[],"_links":{"self":[{"href":"https:\/\/whitemarblegranite.com\/es\/wp-json\/wp\/v2\/adweb_products\/8625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whitemarblegranite.com\/es\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/whitemarblegranite.com\/es\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whitemarblegranite.com\/es\/wp-json\/wp\/v2\/media\/8631"}],"wp:attachment":[{"href":"https:\/\/whitemarblegranite.com\/es\/wp-json\/wp\/v2\/media?parent=8625"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/whitemarblegranite.com\/es\/wp-json\/wp\/v2\/adweb_product_categories?post=8625"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/whitemarblegranite.com\/es\/wp-json\/wp\/v2\/adweb_product_tags?post=8625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}